{"id":4303,"date":"2020-04-09T19:57:19","date_gmt":"2020-04-09T17:57:19","guid":{"rendered":"https:\/\/latambouilledebouille.com\/?post_type=cp_recipe&#038;p=4303"},"modified":"2020-05-19T16:21:45","modified_gmt":"2020-05-19T14:21:45","slug":"gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller","status":"publish","type":"cp_recipe","link":"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/","title":{"rendered":"G\u00e2teau marbr\u00e9 au Van Houten qui d\u00e9chire! Papy Bro\u2019 peut aller se rhabiller!"},"content":{"rendered":"<h2>Le g\u00e2teau marbr\u00e9 au Van Houten qui d\u00e9chire! Papy Bro\u2019 peut aller se rhabiller!<br \/>\nCe g\u00e2teau est parfait pour le go\u00fbter, il ressemble fortement au c\u00e9l\u00e8bre cake marbr\u00e9 du Papy Bro\u2019 (vous aurez reconnu) en meilleur, sans vouloir me vanter! (vous savez que ce n\u2019est pas mon genre).<\/h2>\n<h3>Ingr\u00e9dients<\/h3>\n<div class=\"cooked-recipe-ingredients\">\n<div itemprop=\"recipeIngredient\" class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-amount\" data-decimal=\"130\">130<\/span> <span class=\"cooked-ing-measurement\">g<\/span> <span class=\"cooked-ing-name\">beurre<\/span><\/div>\n<div itemprop=\"recipeIngredient\" class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-amount\" data-decimal=\"180\">180<\/span> <span class=\"cooked-ing-measurement\">g<\/span> <span class=\"cooked-ing-name\">sucre<\/span><\/div>\n<div itemprop=\"recipeIngredient\" class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-amount\" data-decimal=\"3\">3<\/span> <span class=\"cooked-ing-measurement\"><\/span> <span class=\"cooked-ing-name\">oeufs<\/span><\/div>\n<div itemprop=\"recipeIngredient\" class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-amount\" data-decimal=\"6\">6<\/span> <span class=\"cooked-ing-measurement\">cuill\u00e8res \u00e0 soupe<\/span> <span class=\"cooked-ing-name\">lait<\/span><\/div>\n<div itemprop=\"recipeIngredient\" class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-amount\" data-decimal=\"1\">1<\/span> <span class=\"cooked-ing-measurement\">cuill\u00e8re \u00e0 soupe<\/span> <span class=\"cooked-ing-name\">lait pour ajouter au m\u00e9lange chocolat<\/span><\/div>\n<div itemprop=\"recipeIngredient\" class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-amount\" data-decimal=\"200\">200<\/span> <span class=\"cooked-ing-measurement\">g<\/span> <span class=\"cooked-ing-name\">farine<\/span><\/div>\n<div itemprop=\"recipeIngredient\" class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-amount\" data-decimal=\"1\">1<\/span> <span class=\"cooked-ing-measurement\"><\/span> <span class=\"cooked-ing-name\">paquet de levure chimique<\/span><\/div>\n<div itemprop=\"recipeIngredient\" class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-amount\" data-decimal=\"1\">1<\/span> <span class=\"cooked-ing-measurement\"><\/span> <span class=\"cooked-ing-name\">paquet de sucre vanill\u00e9<\/span><\/div>\n<div itemprop=\"recipeIngredient\" class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-amount\" data-decimal=\"40\">40<\/span> <span class=\"cooked-ing-measurement\">g<\/span> <span class=\"cooked-ing-name\"><a target=\"_blank\" href=\"http:\/\/www.vanhouten.fr\/\" rel=\"noopener noreferrer\">de chocolat VanHouten<\/a><\/span><\/div>\n<div itemprop=\"recipeIngredient\" class=\"cooked-single-ingredient cooked-ingredient cooked-ing-no-checkbox\"><span class=\"cooked-ing-name\">quelques gouttes d\u2019extraits de vanille liquide pour la partie blanche.<\/span><\/div>\n<\/div>\n<h3>Instructions<\/h3>\n<div class=\"cooked-recipe-directions\">\n<div class=\"cooked-single-direction cooked-heading\">La p\u00e2te<\/div>\n<div class=\"cooked-single-direction cooked-direction\" data-step=\"Etape 1\">\n<div class=\"cooked-dir-content\">\n<p>Commencer par m\u00e9langer le beurre, le sucre et le sucre vanill\u00e9.<\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-direction\" data-step=\"Etape 2\">\n<div class=\"cooked-dir-content\">\n<p>Ajouter ensuite les jaunes d\u2019oeufs, r\u00e9server les blancs, m\u00e9langer.<\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-direction\" data-step=\"Etape 3\">\n<div class=\"cooked-dir-content\">\n<p>Ajouter ensuite la farine, les 6 cuill\u00e8res \u00e0 soupe de lait et la levure chimique.<br \/>\nBien m\u00e9langer.<\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-direction\" data-step=\"Etape 4\">\n<div class=\"cooked-dir-content\">\n<p>Monter les blancs en neige et ajouter dans votre pr\u00e9paration.<\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-heading\">S\u00e9parer la p\u00e2te en deux<\/div>\n<div class=\"cooked-single-direction cooked-direction\" data-step=\"Etape 5\">\n<div class=\"cooked-dir-content\">\n<p>Dans une partie ajouter quelques gouttes de vanille liquide.<\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-direction\" data-step=\"Etape 6\">\n<div class=\"cooked-dir-content\">\n<p>Dans la seconde ajouter le chocolat et le lait.<\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-heading\">Pr\u00e9paration du moule<\/div>\n<div class=\"cooked-single-direction cooked-direction\" data-step=\"Etape 7\">\n<div class=\"cooked-dir-content\">\n<p>Beurrer et fariner (j\u2019ai mis du sucre \u00e0 la place de la farine) votre moule \u00e0 g\u00e2teau ou \u00e0 cake (j\u2019utiliserai un moule \u00e0 cake la fois prochaine).<\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-heading\">Maintenant passons \u00e0 la partie \u201cremplissage\u201d de moule.<\/div>\n<div class=\"cooked-single-direction cooked-direction cooked-direction-has-image\" data-step=\"Etape 8\">\n<div class=\"ct-direction-image\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"618\" src=\"https:\/\/i0.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615150-1.jpg?resize=800%2C618&#038;ssl=1\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615150-1.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615150-1.jpg?resize=300%2C232&amp;ssl=1 300w, https:\/\/i0.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615150-1.jpg?resize=768%2C593&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div>\n<div class=\"cooked-dir-content\">\n<p>D\u00e9poser une cuill\u00e8re de p\u00e2te clair, puis une cuill\u00e8re de p\u00e2te chocolat au centre du premier rond, recommencer en alternant les p\u00e2tes, toujours en mettant la cuill\u00e8re de p\u00e2te suivante au centre de la pr\u00e9c\u00e9dente.<\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-heading\">Cuisson<\/div>\n<div class=\"cooked-single-direction cooked-direction cooked-direction-has-image\" data-step=\"Etape 9\">\n<div class=\"ct-direction-image\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"800\" height=\"581\" src=\"https:\/\/i0.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615158-1.jpg?resize=800%2C581&#038;ssl=1\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/i2.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615158-1.jpg?w=800&amp;ssl=1 800w, https:\/\/i2.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615158-1.jpg?resize=300%2C218&amp;ssl=1 300w, https:\/\/i2.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615158-1.jpg?resize=768%2C558&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div>\n<div class=\"cooked-dir-content\">\n<p><span class=\"cooked-timer\"><a data-timer-id=\"fad61f291699cdfc5ee5e951fc995b8e_1\" data-seconds=\"0\" data-desc=\" Enfourner \u00e0 180\u00b0 pour 30 minutes. \"><i class=\"cooked-icon cooked-icon-clock\"><\/i>  Enfourner \u00e0 180\u00b0 pour 30 minutes. <\/a><\/span><br \/>\nV\u00e9rifier la cuisson et laisser refroidir.<\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-direction cooked-direction-has-image\" data-step=\"Etape 10\">\n<div class=\"ct-direction-image\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"800\" height=\"677\" src=\"https:\/\/i0.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615188-1.jpg?resize=800%2C677&#038;ssl=1\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/i1.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615188-1.jpg?w=800&amp;ssl=1 800w, https:\/\/i1.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615188-1.jpg?resize=300%2C254&amp;ssl=1 300w, https:\/\/i1.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615188-1.jpg?resize=768%2C650&amp;ssl=1 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div>\n<div class=\"cooked-dir-content\">\n<p>Bon app\u00e9tit! <\/p>\n<\/div>\n<\/div>\n<div class=\"cooked-single-direction cooked-direction cooked-direction-has-image\" data-step=\"Etape 11\">\n<div class=\"ct-direction-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/i0.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615197-1.jpg?resize=600%2C800&#038;ssl=1\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/i2.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615197-1.jpg?w=600&amp;ssl=1 600w, https:\/\/i2.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615197-1.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div>\n<div class=\"cooked-dir-content\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"author":2,"featured_media":1141,"comment_status":"open","ping_status":"closed","template":"","recipe_category":[1816,1819],"cp_thatix_type":[],"class_list":["post-4303","cp_recipe","type-cp_recipe","status-publish","has-post-thumbnail","hentry","cp_recipe_category-chocolat","cp_recipe_category-douceur-sucree"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.0 (Yoast SEO v24.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le g\u00e2teau marbr\u00e9 au Van Houten, ce g\u00e2teau est parfait pour le go\u00fbter, un bon gout de chocolat, avec ses marbrures Un bon go\u00fbt de chocolat, mais avec du Van Houten c\u2019est normal!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"G\u00e2teau marbr\u00e9 au Van Houten qui d\u00e9chire! Papy Bro\u2019 peut aller se rhabiller!\" \/>\n<meta property=\"og:description\" content=\"Le g\u00e2teau marbr\u00e9 au Van Houten qui d\u00e9chire! Papy Bro\u2019 peut aller se rhabiller!  Ce g\u00e2teau est parfait pour le go\u00fbter, il ressemble fortement au c\u00e9l\u00e8bre cake marbr\u00e9 du Papy Bro\u2019 (vous aurez reconnu) en meilleur, sans vouloir me vanter! (vous savez que ce n\u2019est pas mon genre).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/\" \/>\n<meta property=\"og:site_name\" content=\"La tambouille de Bouille\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-19T14:21:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615180-1.jpg?fit=800%2C632&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"632\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/\",\"url\":\"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/\",\"name\":\"Le g\u00e2teau marbr\u00e9 au Van Houten, ce g\u00e2teau est parfait pour le go\u00fbter, un bon gout de chocolat, avec ses marbrures Un bon go\u00fbt de chocolat, mais avec du Van Houten c\u2019est normal!\",\"isPartOf\":{\"@id\":\"https:\/\/latambouilledebouille.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615180-1.jpg?fit=800%2C632&ssl=1\",\"datePublished\":\"2020-04-09T17:57:19+00:00\",\"dateModified\":\"2020-05-19T14:21:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615180-1.jpg?fit=800%2C632&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615180-1.jpg?fit=800%2C632&ssl=1\",\"width\":800,\"height\":632},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/latambouilledebouille.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recettes\",\"item\":\"https:\/\/latambouilledebouille.com\/index.php\/archive-des-recettes\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"G\u00e2teau marbr\u00e9 au Van Houten qui d\u00e9chire! Papy Bro\u2019 peut aller se rhabiller!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/latambouilledebouille.com\/#website\",\"url\":\"https:\/\/latambouilledebouille.com\/\",\"name\":\"La tambouille de Bouille\",\"description\":\"De la gourmandise sucr\u00e9e, sal\u00e9e, avec une pinc\u00e9e de fantaisie\",\"publisher\":{\"@id\":\"https:\/\/latambouilledebouille.com\/#\/schema\/person\/60a785d85a273d47d213dd39e49799d2\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/latambouilledebouille.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/latambouilledebouille.com\/#\/schema\/person\/60a785d85a273d47d213dd39e49799d2\",\"name\":\"BouilledeGum\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/latambouilledebouille.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2b559a9357377a79331e346651242fa8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2b559a9357377a79331e346651242fa8?s=96&d=mm&r=g\",\"caption\":\"BouilledeGum\"},\"logo\":{\"@id\":\"https:\/\/latambouilledebouille.com\/#\/schema\/person\/image\/\"},\"sameAs\":[\"https:\/\/latambouilledebouille.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le g\u00e2teau marbr\u00e9 au Van Houten, ce g\u00e2teau est parfait pour le go\u00fbter, un bon gout de chocolat, avec ses marbrures Un bon go\u00fbt de chocolat, mais avec du Van Houten c\u2019est normal!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/","og_locale":"fr_FR","og_type":"article","og_title":"G\u00e2teau marbr\u00e9 au Van Houten qui d\u00e9chire! Papy Bro\u2019 peut aller se rhabiller!","og_description":"Le g\u00e2teau marbr\u00e9 au Van Houten qui d\u00e9chire! Papy Bro\u2019 peut aller se rhabiller!  Ce g\u00e2teau est parfait pour le go\u00fbter, il ressemble fortement au c\u00e9l\u00e8bre cake marbr\u00e9 du Papy Bro\u2019 (vous aurez reconnu) en meilleur, sans vouloir me vanter! (vous savez que ce n\u2019est pas mon genre).","og_url":"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/","og_site_name":"La tambouille de Bouille","article_modified_time":"2020-05-19T14:21:45+00:00","og_image":[{"width":800,"height":632,"url":"https:\/\/i0.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615180-1.jpg?fit=800%2C632&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/","url":"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/","name":"Le g\u00e2teau marbr\u00e9 au Van Houten, ce g\u00e2teau est parfait pour le go\u00fbter, un bon gout de chocolat, avec ses marbrures Un bon go\u00fbt de chocolat, mais avec du Van Houten c\u2019est normal!","isPartOf":{"@id":"https:\/\/latambouilledebouille.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/#primaryimage"},"image":{"@id":"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615180-1.jpg?fit=800%2C632&ssl=1","datePublished":"2020-04-09T17:57:19+00:00","dateModified":"2020-05-19T14:21:45+00:00","breadcrumb":{"@id":"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/#primaryimage","url":"https:\/\/i0.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615180-1.jpg?fit=800%2C632&ssl=1","contentUrl":"https:\/\/i0.wp.com\/latambouilledebouille.com\/wp-content\/uploads\/2016\/09\/112615180-1.jpg?fit=800%2C632&ssl=1","width":800,"height":632},{"@type":"BreadcrumbList","@id":"https:\/\/latambouilledebouille.com\/index.php\/recipes\/gateau-marbre-au-van-houten-qui-dechire-papy-bro-peut-aller-se-rhabiller\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/latambouilledebouille.com\/"},{"@type":"ListItem","position":2,"name":"Recettes","item":"https:\/\/latambouilledebouille.com\/index.php\/archive-des-recettes\/"},{"@type":"ListItem","position":3,"name":"G\u00e2teau marbr\u00e9 au Van Houten qui d\u00e9chire! Papy Bro\u2019 peut aller se rhabiller!"}]},{"@type":"WebSite","@id":"https:\/\/latambouilledebouille.com\/#website","url":"https:\/\/latambouilledebouille.com\/","name":"La tambouille de Bouille","description":"De la gourmandise sucr\u00e9e, sal\u00e9e, avec une pinc\u00e9e de fantaisie","publisher":{"@id":"https:\/\/latambouilledebouille.com\/#\/schema\/person\/60a785d85a273d47d213dd39e49799d2"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/latambouilledebouille.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/latambouilledebouille.com\/#\/schema\/person\/60a785d85a273d47d213dd39e49799d2","name":"BouilledeGum","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/latambouilledebouille.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2b559a9357377a79331e346651242fa8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b559a9357377a79331e346651242fa8?s=96&d=mm&r=g","caption":"BouilledeGum"},"logo":{"@id":"https:\/\/latambouilledebouille.com\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/latambouilledebouille.com"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/latambouilledebouille.com\/index.php\/wp-json\/wp\/v2\/cooked_recipe\/4303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latambouilledebouille.com\/index.php\/wp-json\/wp\/v2\/cooked_recipe"}],"about":[{"href":"https:\/\/latambouilledebouille.com\/index.php\/wp-json\/wp\/v2\/types\/cp_recipe"}],"author":[{"embeddable":true,"href":"https:\/\/latambouilledebouille.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/latambouilledebouille.com\/index.php\/wp-json\/wp\/v2\/comments?post=4303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latambouilledebouille.com\/index.php\/wp-json\/wp\/v2\/media\/1141"}],"wp:attachment":[{"href":"https:\/\/latambouilledebouille.com\/index.php\/wp-json\/wp\/v2\/media?parent=4303"}],"wp:term":[{"taxonomy":"cp_recipe_category","embeddable":true,"href":"https:\/\/latambouilledebouille.com\/index.php\/wp-json\/wp\/v2\/recipe_category?post=4303"},{"taxonomy":"cp_thatix_type","embeddable":true,"href":"https:\/\/latambouilledebouille.com\/index.php\/wp-json\/wp\/v2\/cp_thatix_type?post=4303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}